{"id":1491,"date":"2024-10-27T11:38:29","date_gmt":"2024-10-27T11:38:29","guid":{"rendered":"https:\/\/bonuskongcasino.com\/privacy-policy\/"},"modified":"2026-02-27T09:41:26","modified_gmt":"2026-02-27T09:41:26","slug":"informativa-sulla-privacy","status":"publish","type":"page","link":"https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/","title":{"rendered":"Informativa sulla Privacy"},"content":{"rendered":"<h1>Informativa sulla privacy<\/h1>\n<h2>Chi siamo<\/h2>\n<p>L&#8217;indirizzo del nostro sito web \u00e8: rollambia.net.<\/p>\n<h2>Commenti<\/h2>\n<p>Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti, nonch\u00e9 l&#8217;indirizzo IP e la stringa dello user agent dei visitatori per facilitare il rilevamento dello spam.<\/p>\n<p>Una stringa anonima creata a partire dal vostro indirizzo e-mail (chiamata anche hash) pu\u00f2 essere fornita al servizio Gravatar per verificare se lo state utilizzando. L&#8217;informativa sulla privacy di Gravatar \u00e8 disponibile qui: https:\/\/automattic.com\/privacy\/. Una volta approvato il commento, l&#8217;immagine del profilo sar\u00e0 visibile al pubblico nel contesto del commento stesso.<\/p>\n<h2>File multimediali<\/h2>\n<p>Se si caricano immagini sul sito, si dovrebbe evitare di caricare immagini con dati di localizzazione incorporati (EXIF GPS). I visitatori del sito possono scaricare ed estrarre i dati di localizzazione dalle immagini presenti sul sito.<\/p>\n<h2>Cookie<\/h2>\n<p>Se lasciate un commento sul nostro sito, potete scegliere di salvare il vostro nome, indirizzo e-mail e sito web nei cookie. Questo per comodit\u00e0 dell&#8217;utente, in modo che non debba inserire nuovamente i propri dati al prossimo commento. La durata di questi cookie \u00e8 di 1 anno.<\/p>\n<p>Se avete un account sul sito e vi loggate, imposteremo un cookie temporaneo per determinare se il vostro browser supporta i cookie; il cookie non contiene dati personali e viene cancellato quando chiudete il browser.<\/p>\n<p>Quando si accede al sito, vengono impostati anche diversi cookie per salvare le informazioni relative al login e alle impostazioni dello schermo. I cookie di accesso durano 2 giorni e i cookie delle impostazioni dello schermo durano 1 anno. Se si seleziona \u201cRicordami\u201d, il login durer\u00e0 2 settimane. Se si esce dal proprio account, i cookie di accesso verranno cancellati.<\/p>\n<p>Se modificate o pubblicate un articolo, nel vostro browser verr\u00e0 salvato un ulteriore cookie. Questo cookie non contiene dati personali e indica semplicemente l&#8217;ID del post dell&#8217;articolo appena modificato. Scade tra 1 giorno.<\/p>\n<h2>Contenuti incorporati da altri siti web<\/h2>\n<p>Gli articoli di questo sito possono contenere contenuti incorporati (ad esempio video, immagini, articoli, ecc.). I contenuti incorporati di altri siti web si comportano esattamente come se l&#8217;utente avesse visitato l&#8217;altro sito web.<\/p>\n<p>Questi siti possono raccogliere dati sull&#8217;utente, utilizzare cookie, incorporare applicazioni di tracciamento di terze parti e monitorare l&#8217;interazione dell&#8217;utente con i contenuti incorporati. In particolare, tracciano l&#8217;interazione dell&#8217;utente con il contenuto incorporato se l&#8217;utente possiede un account e ha effettuato l&#8217;accesso al sito web in questione.<\/p>\n<h2>Con chi condividiamo i vostri dati?<\/h2>\n<p>Se richiedete una reimpostazione della password, il vostro indirizzo IP sar\u00e0 incluso nell&#8217;e-mail di reimpostazione della password.<\/p>\n<h2>Per quanto tempo conserviamo i vostri dati?<\/h2>\n<p>Se lasciate un commento, il commento e i suoi metadati vengono conservati a tempo indeterminato. Questo ci permette di identificare e approvare automaticamente i commenti successivi, invece di tenerli in coda di moderazione.<\/p>\n<p>Per gli utenti che si registrano sul nostro sito (se presenti), memorizziamo le informazioni personali fornite nel loro profilo utente. Tutti gli utenti possono visualizzare, modificare o cancellare le proprie informazioni personali in qualsiasi momento (tranne che per il fatto che non possono cambiare il proprio nome utente). Anche gli amministratori del sito possono visualizzare e modificare tali informazioni.<\/p>\n<h2>Quali sono i diritti dell&#8217;utente in merito ai propri dati?<\/h2>\n<p>Se avete un account su questo sito o avete lasciato commenti, potete richiedere di ricevere un file esportato dei dati personali in nostro possesso, compresi quelli che ci avete fornito. Potete anche richiedere la cancellazione dei dati personali in nostro possesso. Questo non include i dati che siamo tenuti a conservare per scopi amministrativi, legali o di sicurezza.<\/p>\n<h2>Dove vengono inviati i vostri dati<\/h2>\n<p>I commenti dei visitatori possono essere controllati da un servizio automatico di rilevamento dello spam.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informativa sulla privacy Chi siamo L&#8217;indirizzo del nostro sito web \u00e8: rollambia.net. Commenti Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti, nonch\u00e9 l&#8217;indirizzo IP e la stringa dello user agent dei visitatori per facilitare il rilevamento dello spam. Una stringa anonima creata a partire dal vostro indirizzo e-mail [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"template-builder.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1491","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informativa sulla Privacy<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;Informativa sulla privacy: come vengono raccolti, utilizzati e protetti i tuoi dati personali per garantire un&#039;esperienza di gioco sicura.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informativa sulla Privacy\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;Informativa sulla privacy: come vengono raccolti, utilizzati e protetti i tuoi dati personali per garantire un&#039;esperienza di gioco sicura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"Rollambia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T09:41:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/informativa-sulla-privacy\\\/\",\"url\":\"https:\\\/\\\/rollambia.net\\\/it\\\/informativa-sulla-privacy\\\/\",\"name\":\"Informativa sulla Privacy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/#website\"},\"datePublished\":\"2024-10-27T11:38:29+00:00\",\"dateModified\":\"2026-02-27T09:41:26+00:00\",\"description\":\"Scopri l'Informativa sulla privacy: come vengono raccolti, utilizzati e protetti i tuoi dati personali per garantire un'esperienza di gioco sicura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rollambia.net\\\/it\\\/informativa-sulla-privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/informativa-sulla-privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Rollambia\",\"item\":\"https:\\\/\\\/rollambia.net\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informativa sulla Privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/rollambia.net\\\/it\\\/\",\"name\":\"Rollambia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rollambia.net\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/#organization\",\"name\":\"Rollambia\",\"url\":\"https:\\\/\\\/rollambia.net\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rollambia.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cropped-logo-e1772095679432-1.png\",\"contentUrl\":\"https:\\\/\\\/rollambia.net\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cropped-logo-e1772095679432-1.png\",\"width\":206,\"height\":47,\"caption\":\"Rollambia\"},\"image\":{\"@id\":\"https:\\\/\\\/rollambia.net\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informativa sulla Privacy","description":"Scopri l'Informativa sulla privacy: come vengono raccolti, utilizzati e protetti i tuoi dati personali per garantire un'esperienza di gioco sicura.","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Informativa sulla Privacy","og_description":"Scopri l'Informativa sulla privacy: come vengono raccolti, utilizzati e protetti i tuoi dati personali per garantire un'esperienza di gioco sicura.","og_url":"https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/","og_site_name":"Rollambia","article_modified_time":"2026-02-27T09:41:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/","url":"https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/","name":"Informativa sulla Privacy","isPartOf":{"@id":"https:\/\/rollambia.net\/it\/#website"},"datePublished":"2024-10-27T11:38:29+00:00","dateModified":"2026-02-27T09:41:26+00:00","description":"Scopri l'Informativa sulla privacy: come vengono raccolti, utilizzati e protetti i tuoi dati personali per garantire un'esperienza di gioco sicura.","breadcrumb":{"@id":"https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rollambia.net\/it\/informativa-sulla-privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Rollambia","item":"https:\/\/rollambia.net\/it\/"},{"@type":"ListItem","position":2,"name":"Informativa sulla Privacy"}]},{"@type":"WebSite","@id":"https:\/\/rollambia.net\/it\/#website","url":"https:\/\/rollambia.net\/it\/","name":"Rollambia","description":"","publisher":{"@id":"https:\/\/rollambia.net\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rollambia.net\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/rollambia.net\/it\/#organization","name":"Rollambia","url":"https:\/\/rollambia.net\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rollambia.net\/it\/#\/schema\/logo\/image\/","url":"https:\/\/rollambia.net\/wp-content\/uploads\/2026\/02\/cropped-logo-e1772095679432-1.png","contentUrl":"https:\/\/rollambia.net\/wp-content\/uploads\/2026\/02\/cropped-logo-e1772095679432-1.png","width":206,"height":47,"caption":"Rollambia"},"image":{"@id":"https:\/\/rollambia.net\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/pages\/1491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/comments?post=1491"}],"version-history":[{"count":2,"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/pages\/1491\/revisions"}],"predecessor-version":[{"id":2152,"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/pages\/1491\/revisions\/2152"}],"wp:attachment":[{"href":"https:\/\/rollambia.net\/it\/wp-json\/wp\/v2\/media?parent=1491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}